{"id":1025,"date":"2026-09-01T16:25:37","date_gmt":"2026-09-01T14:25:37","guid":{"rendered":"https:\/\/leo-windeln.de\/?post_type=kunstwerke&#038;p=1025"},"modified":"2026-09-01T16:27:48","modified_gmt":"2026-09-01T14:27:48","slug":"1025","status":"publish","type":"kunstwerke","link":"https:\/\/leo-windeln.de\/en\/kunstwerke\/1025\/","title":{"rendered":"Windm\u00fchle mit Mohnblumenfeld"},"template":"","meta":{"_acf_changed":false},"veroeffentlichungsjahre":[74],"class_list":["post-1025","kunstwerke","type-kunstwerke","status-publish","hentry","veroeffentlichungsjahre-74"],"acf":[],"_links":{"self":[{"href":"https:\/\/leo-windeln.de\/en\/wp-json\/wp\/v2\/kunstwerke\/1025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leo-windeln.de\/en\/wp-json\/wp\/v2\/kunstwerke"}],"about":[{"href":"https:\/\/leo-windeln.de\/en\/wp-json\/wp\/v2\/types\/kunstwerke"}],"version-history":[{"count":2,"href":"https:\/\/leo-windeln.de\/en\/wp-json\/wp\/v2\/kunstwerke\/1025\/revisions"}],"predecessor-version":[{"id":1028,"href":"https:\/\/leo-windeln.de\/en\/wp-json\/wp\/v2\/kunstwerke\/1025\/revisions\/1028"}],"wp:attachment":[{"href":"https:\/\/leo-windeln.de\/en\/wp-json\/wp\/v2\/media?parent=1025"}],"wp:term":[{"taxonomy":"veroeffentlichungsjahre","embeddable":true,"href":"https:\/\/leo-windeln.de\/en\/wp-json\/wp\/v2\/veroeffentlichungsjahre?post=1025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}